{"id":1387,"date":"2025-01-03T18:59:44","date_gmt":"2025-01-03T17:59:44","guid":{"rendered":"https:\/\/vfl-schlangen.de\/tischtennis\/?p=1387"},"modified":"2025-01-03T18:59:44","modified_gmt":"2025-01-03T17:59:44","slug":"neujahrsturnier-2025-abgesagt","status":"publish","type":"post","link":"https:\/\/vfl-schlangen.de\/tischtennis\/2025\/01\/03\/neujahrsturnier-2025-abgesagt\/","title":{"rendered":"Neujahrsturnier 2025 abgesagt"},"content":{"rendered":"\n<p>Das Jahr startet leider mit einer schlechten Nachricht f\u00fcr uns Tischtennis begeisterten Sportler vom VfL und den eingeladenen Teams unseres Neujahrsturnieres. Die Heizung in der gro\u00dfen Halle ist defekt und dadurch haben wir nur 10 Grad dort. Die Gemeinde ist wegen einer L\u00f6sung in Verbindung mit einer  Firma f\u00fcr Heiz- und Klimatechnik gewesen. Aber leider gibt es kurzfristig keine L\u00f6sung f\u00fcr das Problem, es ist eine gr\u00f6\u00dfere Sache die l\u00e4nger dauert.<\/p>\n\n\n\n<p>Auch der VfL Vorstand hat versucht etwas in die Wege zu leiten, damit die Halle warm wird und unser Neujahrsturnier stattfinden kann. leider auch erfolglos.&nbsp;<\/p>\n\n\n\n<p>Alternativ laden wir euch, gerne mit der Familie, Partner, am Sonntag auf 12.00 Uhr in das Foyer der Rennekamphalle zu einem gem\u00fctlichen Nachmittag ein. Ab ca 13.00 Uhr wird der Film, der w\u00e4hrend des Festkommers anl\u00e4sslich des VfL Jubil\u00e4ums gedreht wurde, auf der gro\u00dfen Leinwand gezeigt.&nbsp;<\/p>\n\n\n\n<p>F\u00fcr das leibliche Wohl ist gesorgt. Es gibt Kaltgetr\u00e4nke, Salate, Hei\u00dfwurst, Kaffee und Kuchen.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Jahr startet leider mit einer schlechten Nachricht f\u00fcr uns Tischtennis begeisterten Sportler vom VfL und den eingeladenen Teams unseres Neujahrsturnieres. Die Heizung in der gro\u00dfen Halle ist defekt und dadurch haben wir nur 10 Grad dort. Die Gemeinde ist wegen einer L\u00f6sung in Verbindung mit einer Firma f\u00fcr Heiz- und Klimatechnik gewesen. Aber leider [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tpgb_global_settings":"","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1387","post","type-post","status-publish","format-standard","hentry","category-allgemein","entry"],"tpgb_featured_images":null,"tpgb_post_meta_info":{"get_date":"3. Januar 2025","get_modified_date":"3. Januar 2025","category_list":{"category":[{"term_id":1,"name":"Allgemein","slug":"allgemein","term_group":0,"term_taxonomy_id":1,"taxonomy":"category","description":"","parent":0,"count":14,"filter":"raw"}],"post_tag":false,"post_format":false},"author_name":"Frank Wirtz","author_url":"https:\/\/vfl-schlangen.de\/tischtennis\/author\/fwirtz\/","author_email":"frank.wirtz@googlemail.com","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"Frank","author_lastname":"Wirtz","user_login":"fwirtz","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/ccfd0ea2a05aca52345396638f0525ea881ebe2be2b213a61784e8983ef36410?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/ccfd0ea2a05aca52345396638f0525ea881ebe2be2b213a61784e8983ef36410?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/ccfd0ea2a05aca52345396638f0525ea881ebe2be2b213a61784e8983ef36410?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"category":"<a href=\"https:\/\/vfl-schlangen.de\/tischtennis\/category\/allgemein\/\" alt=\"Allgemein\"  class=\"category-allgemein\">Allgemein<\/a> "},"categories_names":["Allgemein"],"post_class":[["post-1387","post","type-post","status-publish","format-standard","hentry","category-allgemein","entry"]],"author_avatar":["<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/ccfd0ea2a05aca52345396638f0525ea881ebe2be2b213a61784e8983ef36410?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/ccfd0ea2a05aca52345396638f0525ea881ebe2be2b213a61784e8983ef36410?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' decoding='async'\/>"],"featured_video":null,"_links":{"self":[{"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/posts\/1387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/comments?post=1387"}],"version-history":[{"count":1,"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/posts\/1387\/revisions"}],"predecessor-version":[{"id":1388,"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/posts\/1387\/revisions\/1388"}],"wp:attachment":[{"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/media?parent=1387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/categories?post=1387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/tags?post=1387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}