{"id":1332,"date":"2023-12-18T19:17:41","date_gmt":"2023-12-18T18:17:41","guid":{"rendered":"https:\/\/vfl-schlangen.de\/tischtennis\/?p=1332"},"modified":"2023-12-18T19:17:41","modified_gmt":"2023-12-18T18:17:41","slug":"kleiner-rueckblick-auf-die-hinserie-2023-24","status":"publish","type":"post","link":"https:\/\/vfl-schlangen.de\/tischtennis\/2023\/12\/18\/kleiner-rueckblick-auf-die-hinserie-2023-24\/","title":{"rendered":"Kleiner R\u00fcckblick auf die Hinserie 2023\/24"},"content":{"rendered":"\n<p>Die Tischtennisspieler des VfL Schlangen haben bei einer Wanderung mit anschlie\u00dfenden Verzehr einer Suppe rustikal die Hinserie 2023\/24 ausklingen lassen. Dabei wurde auch \u00fcber den Verlauf des Spiel- und Trainingsbetriebs diskutiert.<\/p>\n\n\n\n<p>In der Trainingsleitung unserer Jugendabteilung gab es einen Wechsel. Michael Kottnik hat den Posten von Bastian Voss \u00fcbernommen. Beim Jugendtraining montags von 18.00 bis 19.30 Uhr wird er regelm\u00e4\u00dfig von 2 Spielern aus dem Erwachsenenbereich unterst\u00fctzt. Es kommen 10 bis 14 Jugendliche und Sch\u00fcler in die Schulturnhalle, um sich mit dem kleinen wei\u00dfen Ball zu besch\u00e4ftigen.<\/p>\n\n\n\n<p>Zum anschlie\u00dfenden Erwachsenentraining ab 19.30 Uhr kommen regelm\u00e4\u00dfig 7 bis 10 Herren und Damen in die Schulturnhalle.<br>Unsere <strong>1. Mannschaft<\/strong> musste in den Spielen immer auf Spieler aus der 2. oder 3. Mannschaft zur Verst\u00e4rkung zur\u00fcckgreifen. Es gelang ihnen leider nur 1 Sieg und ein Unentschieden in 9 Spielen, somit belegen sie den 10. Platz in der 2. Bezirksklasse.<\/p>\n\n\n\n<p>Die <strong>2. Mannschaft<\/strong> spielte sehr erfolgreich in der 4. Bezirksklasse. Sie f\u00fchren die Tabelle mit einem Minuspunkt an. Den direkten Vergleich im Derby gegen unsere 3. Mannschaft gewannen sie mit 6:4. <\/p>\n\n\n\n<p>Die <strong>3. Mannschaft<\/strong> belegt zur Zeit den 4. Tabellenplatz in der selben Klasse. In der Pokalspielrunde erreichte die 2.Mannschaft das Endspiel in der 4. Bezirksklasse. Dieses findet am 21. Januar 2024 ab 11.00 Uhr in Brakel gegen DJK Nieheim 5 statt.<\/p>\n\n\n\n<p>Nun freuen sich alle aus der Tischtennisabteilung auf das <strong>Neujahrsturnier am 7. Januar<\/strong> in der Rennekamphalle, zu dem wieder einige Teams aus den Kreisen Lippe und Paderborn eingeladen sind. Ende Juni findet unser j\u00e4hrliches Treffen mit den Tischtennisspielern des <strong>Boocker SV 62<\/strong> statt, diesmal fahren wir wieder zu ihnen an die polnische Grenze.<\/p>\n\n\n\n<p><em>Wir w\u00fcnschen eine sch\u00f6ne und besinnliche Weihnachtszeit und einen guten Start in das Jahr 2024.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Tischtennisspieler des VfL Schlangen haben bei einer Wanderung mit anschlie\u00dfenden Verzehr einer Suppe rustikal die Hinserie 2023\/24 ausklingen lassen. Dabei wurde auch \u00fcber den Verlauf des Spiel- und Trainingsbetriebs diskutiert. In der Trainingsleitung unserer Jugendabteilung gab es einen Wechsel. Michael Kottnik hat den Posten von Bastian Voss \u00fcbernommen. Beim Jugendtraining montags von 18.00 bis [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":1333,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tpgb_global_settings":"","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","entry","has-media"],"tpgb_featured_images":{"full":["https:\/\/vfl-schlangen.de\/tischtennis\/wp-content\/uploads\/sites\/5\/2023\/12\/tischtennisabteilung-vfl-schlangen-winterspass.jpg",1024,768,false],"tp-image-grid":["https:\/\/vfl-schlangen.de\/tischtennis\/wp-content\/uploads\/sites\/5\/2023\/12\/tischtennisabteilung-vfl-schlangen-winterspass-700x700.jpg",700,700,true],"thumbnail":["https:\/\/vfl-schlangen.de\/tischtennis\/wp-content\/uploads\/sites\/5\/2023\/12\/tischtennisabteilung-vfl-schlangen-winterspass-150x150.jpg",150,150,true],"medium":["https:\/\/vfl-schlangen.de\/tischtennis\/wp-content\/uploads\/sites\/5\/2023\/12\/tischtennisabteilung-vfl-schlangen-winterspass-300x225.jpg",300,225,true],"medium_large":["https:\/\/vfl-schlangen.de\/tischtennis\/wp-content\/uploads\/sites\/5\/2023\/12\/tischtennisabteilung-vfl-schlangen-winterspass-768x576.jpg",768,576,true],"large":["https:\/\/vfl-schlangen.de\/tischtennis\/wp-content\/uploads\/sites\/5\/2023\/12\/tischtennisabteilung-vfl-schlangen-winterspass.jpg",1024,768,false],"default":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-content\/plugins\/the-plus-addons-for-block-editor\/assets\/images\/tpgb-placeholder.jpg"},"tpgb_post_meta_info":{"get_date":"18. Dezember 2023","get_modified_date":"18. Dezember 2023","category_list":{"category":[{"term_id":1,"name":"Allgemein","slug":"allgemein","term_group":0,"term_taxonomy_id":1,"taxonomy":"category","description":"","parent":0,"count":14,"filter":"raw"}],"post_tag":false,"post_format":false},"author_name":"Frank Wirtz","author_url":"https:\/\/vfl-schlangen.de\/tischtennis\/author\/fwirtz\/","author_email":"frank.wirtz@googlemail.com","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"Frank","author_lastname":"Wirtz","user_login":"fwirtz","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/ccfd0ea2a05aca52345396638f0525ea881ebe2be2b213a61784e8983ef36410?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/ccfd0ea2a05aca52345396638f0525ea881ebe2be2b213a61784e8983ef36410?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/ccfd0ea2a05aca52345396638f0525ea881ebe2be2b213a61784e8983ef36410?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"category":"<a href=\"https:\/\/vfl-schlangen.de\/tischtennis\/category\/allgemein\/\" alt=\"Allgemein\"  class=\"category-allgemein\">Allgemein<\/a> "},"categories_names":["Allgemein"],"post_class":[["post-1332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","entry","has-media"]],"author_avatar":["<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/ccfd0ea2a05aca52345396638f0525ea881ebe2be2b213a61784e8983ef36410?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/ccfd0ea2a05aca52345396638f0525ea881ebe2be2b213a61784e8983ef36410?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' decoding='async'\/>"],"featured_video":null,"_links":{"self":[{"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/posts\/1332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/comments?post=1332"}],"version-history":[{"count":2,"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/posts\/1332\/revisions"}],"predecessor-version":[{"id":1335,"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/posts\/1332\/revisions\/1335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/media\/1333"}],"wp:attachment":[{"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/media?parent=1332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/categories?post=1332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vfl-schlangen.de\/tischtennis\/wp-json\/wp\/v2\/tags?post=1332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}