{"id":2125,"date":"2025-12-17T20:42:19","date_gmt":"2025-12-17T19:42:19","guid":{"rendered":"https:\/\/vfl-schlangen.de\/handball\/?p=2125"},"modified":"2025-12-17T20:42:19","modified_gmt":"2025-12-17T19:42:19","slug":"was-fuer-ein-fight-bei-den-damen-%f0%9f%94%a5","status":"publish","type":"post","link":"https:\/\/vfl-schlangen.de\/handball\/2025\/12\/17\/was-fuer-ein-fight-bei-den-damen-%f0%9f%94%a5\/","title":{"rendered":"Was f\u00fcr ein Fight bei den Damen \ud83d\udd25"},"content":{"rendered":"\n<p>In einem intensiven Spiel haben wir uns vergangenen Sonntag den Sieg gegen die Tabellennachbarn aus Halle geholt.&nbsp;<\/p>\n\n\n\n<p>Von der ersten Minute an war klar: Beide Teams wollten das Ding gewinnen. Nach 15 Minuten konnten wir uns knapp absetzen und lagen mit 5:4 vorne. Die Partie blieb eng, aber wir behielten die Kontrolle und gingen mit einer verdienten 12:9-F\u00fchrung in die Pause.<\/p>\n\n\n\n<p>Auch nach dem Seitenwechsel schenkten sich beide Mannschaften weiterhin nichts. Das Spiel blieb bis in die Schlussminuten spannend und jeder Ball z\u00e4hlte. Am Ende haben wir als Team einen k\u00fchlen Kopf bewahren k\u00f6nnen, alles reingeworfen und uns f\u00fcr den Einsatz \u00fcber die 60 Minuten Spielzeit belohnt.<\/p>\n\n\n\n<p>Wir gewinnen ein intensives Spiel gegen die 2. Damen aus Halle mit 28:25 \u2013 starke Leistung, starke Mannschaft, starker Heimauftritt \ud83d\udcaa\ud83d\udd25<\/p>\n\n\n\n<p>Wir verabschieden uns in die Winterpause, w\u00fcnschen allen Fans und Unterst\u00fctzern des Handballs frohe Weihnachten und einen guten Rutsch ins neue Jahr! \ud83c\udf84\ud83c\udf85<\/p>\n\n\n\n<p>Im neuen Jahr starten wir zun\u00e4chst mit der n\u00e4chsten Runde im Pokal, welches am 10. oder 11. Januar ausw\u00e4rts in Sennelager gegen die Damen der SGH Paderborn stattfinden wird<\/p>\n\n\n\n<p><\/p>\n\n\n<div  class=\"tpgb-container-row tpgb-block-title6a0423752241c    alignwide   tpgb-container-wide \" data-id=\"title6a0423752241c \"   ><div class=\"tpgb-cont-in\"><\/div><\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In einem intensiven Spiel haben wir uns vergangenen Sonntag den Sieg gegen die Tabellennachbarn aus Halle geholt.&nbsp; Von der ersten Minute an war klar: Beide Teams wollten das Ding gewinnen. Nach 15 Minuten konnten wir uns knapp absetzen und lagen mit 5:4 vorne. Die Partie blieb eng, aber wir behielten die Kontrolle und gingen mit [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1817,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tpgb_global_settings":"","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","osp_disable_panel":"default","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[26],"tags":[],"class_list":["post-2125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spielberichte","entry","has-media"],"tpgb_featured_images":{"full":["https:\/\/vfl-schlangen.de\/handball\/wp-content\/uploads\/sites\/2\/2025\/04\/HeaderDamen09.png",800,250,false],"tp-image-grid":["https:\/\/vfl-schlangen.de\/handball\/wp-content\/uploads\/sites\/2\/2025\/04\/HeaderDamen09-700x700.png",700,700,true],"thumbnail":["https:\/\/vfl-schlangen.de\/handball\/wp-content\/uploads\/sites\/2\/2025\/04\/HeaderDamen09-150x150.png",150,150,true],"medium":["https:\/\/vfl-schlangen.de\/handball\/wp-content\/uploads\/sites\/2\/2025\/04\/HeaderDamen09-300x94.png",300,94,true],"medium_large":["https:\/\/vfl-schlangen.de\/handball\/wp-content\/uploads\/sites\/2\/2025\/04\/HeaderDamen09-768x240.png",768,240,true],"large":["https:\/\/vfl-schlangen.de\/handball\/wp-content\/uploads\/sites\/2\/2025\/04\/HeaderDamen09.png",800,250,false],"default":"https:\/\/vfl-schlangen.de\/handball\/wp-content\/plugins\/the-plus-addons-for-block-editor\/assets\/images\/tpgb-placeholder.jpg"},"tpgb_post_meta_info":{"get_date":"17. Dezember 2025","get_modified_date":"17. Dezember 2025","category_list":{"category":[{"term_id":26,"name":"Spielberichte","slug":"spielberichte","term_group":0,"term_taxonomy_id":26,"taxonomy":"category","description":"","parent":0,"count":200,"filter":"raw"}],"post_tag":false,"post_format":false},"author_name":"Matthias L\u00fcning","author_url":"https:\/\/vfl-schlangen.de\/handball\/author\/mluening\/","author_email":"mluening@gmail.com","author_website":"","author_description":"","author_facebook":"","author_twitter":"","author_instagram":"","author_role":["administrator"],"author_firstname":"Matthias","author_lastname":"L\u00fcning","user_login":"mluening","author_avatar":"<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/ee1b6890c1586bf1178a9474cec1037ceda8f36364c8245e6a41e79a446de593?s=200&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/ee1b6890c1586bf1178a9474cec1037ceda8f36364c8245e6a41e79a446de593?s=400&#038;d=mm&#038;r=g 2x' class='avatar avatar-200 photo' height='200' width='200' decoding='async'\/>","author_avatar_url":"https:\/\/secure.gravatar.com\/avatar\/ee1b6890c1586bf1178a9474cec1037ceda8f36364c8245e6a41e79a446de593?s=96&d=mm&r=g","comment_count":0,"post_likes":0,"post_views":0},"tpgb_post_category":{"category":"<a href=\"https:\/\/vfl-schlangen.de\/handball\/category\/spielberichte\/\" alt=\"Spielberichte\"  class=\"category-spielberichte\">Spielberichte<\/a> "},"categories_names":["Spielberichte"],"post_class":[["post-2125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spielberichte","entry","has-media"]],"author_avatar":["<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/ee1b6890c1586bf1178a9474cec1037ceda8f36364c8245e6a41e79a446de593?s=96&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/ee1b6890c1586bf1178a9474cec1037ceda8f36364c8245e6a41e79a446de593?s=192&#038;d=mm&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' decoding='async'\/>"],"featured_video":null,"_links":{"self":[{"href":"https:\/\/vfl-schlangen.de\/handball\/wp-json\/wp\/v2\/posts\/2125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vfl-schlangen.de\/handball\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vfl-schlangen.de\/handball\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vfl-schlangen.de\/handball\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vfl-schlangen.de\/handball\/wp-json\/wp\/v2\/comments?post=2125"}],"version-history":[{"count":1,"href":"https:\/\/vfl-schlangen.de\/handball\/wp-json\/wp\/v2\/posts\/2125\/revisions"}],"predecessor-version":[{"id":2126,"href":"https:\/\/vfl-schlangen.de\/handball\/wp-json\/wp\/v2\/posts\/2125\/revisions\/2126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vfl-schlangen.de\/handball\/wp-json\/wp\/v2\/media\/1817"}],"wp:attachment":[{"href":"https:\/\/vfl-schlangen.de\/handball\/wp-json\/wp\/v2\/media?parent=2125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vfl-schlangen.de\/handball\/wp-json\/wp\/v2\/categories?post=2125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vfl-schlangen.de\/handball\/wp-json\/wp\/v2\/tags?post=2125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}